{"id":423,"date":"2026-02-09T06:27:47","date_gmt":"2026-02-09T06:27:47","guid":{"rendered":"https:\/\/deva.cz\/?page_id=423"},"modified":"2026-03-20T10:31:42","modified_gmt":"2026-03-20T09:31:42","slug":"%d1%80%d0%be%d0%b1%d0%be%d1%87%d1%96-%d0%bc%d1%96%d1%81%d1%86%d1%8f","status":"publish","type":"page","link":"https:\/\/deva.cz\/uk\/jobs\/","title":{"rendered":"\u0420\u043e\u0431\u043e\u0447\u0456 \u043c\u0456\u0441\u0446\u044f"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"423\" class=\"elementor elementor-423\">\n\t\t\t\t<div class=\"elementor-element elementor-element-yhww64u8 twbb_section e-flex e-con-boxed e-con e-parent\" data-id=\"yhww64u8\" data-element_type=\"container\" data-e-type=\"container\" id=\"join-the-deva-nutrition-family\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-pb2am8yd e-con-full e-flex e-con e-child\" data-id=\"pb2am8yd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dh00wepg elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dh00wepg\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u041f\u0440\u0438\u0454\u0434\u043d\u0443\u0439\u0442\u0435\u0441\u044c \u0434\u043e \u043d\u0430\u0448\u043e\u0457 \u043a\u043e\u043c\u0430\u043d\u0434\u0438 \u0432 Deva Nutrition<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1l46kgvu elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1l46kgvu\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0421\u0442\u0430\u043d\u044c\u0442\u0435 \u0447\u0430\u0441\u0442\u0438\u043d\u043e\u044e \u0432\u0456\u0434\u0434\u0430\u043d\u043e\u0457 \u043a\u043e\u043c\u0430\u043d\u0434\u0438, \u044f\u043a\u0430 \u043f\u0440\u0430\u0433\u043d\u0435 \u0434\u043e \u044f\u043a\u043e\u0441\u0442\u0456, \u0441\u0442\u0430\u043b\u043e\u0433\u043e \u0440\u043e\u0437\u0432\u0438\u0442\u043a\u0443 \u0442\u0430 \u0456\u043d\u043d\u043e\u0432\u0430\u0446\u0456\u0439. \u0423 \u043a\u043e\u043c\u043f\u0430\u043d\u0456\u0457 Deva Nutrition a.s. \u043c\u0438 \u0441\u0442\u0432\u043e\u0440\u044e\u0454\u043c\u043e \u0430\u0442\u043c\u043e\u0441\u0444\u0435\u0440\u0443 \u0441\u043f\u0456\u0432\u043f\u0440\u0430\u0446\u0456 \u0442\u0430 \u0456\u043d\u043a\u043b\u044e\u0437\u0438\u0432\u043d\u043e\u0433\u043e \u0440\u043e\u0431\u043e\u0447\u043e\u0433\u043e \u0441\u0435\u0440\u0435\u0434\u043e\u0432\u0438\u0449\u0430, \u0434\u0435 \u0432\u0430\u0448 \u0432\u043d\u0435\u0441\u043e\u043a \u0434\u043e\u043f\u043e\u043c\u0430\u0433\u0430\u0454 \u043d\u0430\u043c \u043f\u043e\u0441\u0442\u0430\u0447\u0430\u0442\u0438 \u0437\u0434\u043e\u0440\u043e\u0432\u0456, \u043e\u0440\u0433\u0430\u043d\u0456\u0447\u043d\u0456 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0438 \u043f\u043e \u0432\u0441\u044c\u043e\u043c\u0443 \u0441\u0432\u0456\u0442\u0443. \u0412\u0456\u0434\u043a\u0440\u0438\u0439\u0442\u0435 \u0434\u043b\u044f \u0441\u0435\u0431\u0435 \u043f\u0435\u0440\u0435\u0432\u0430\u0433\u0438 \u0441\u043f\u0456\u0432\u043f\u0440\u0430\u0446\u0456 \u0437 \u0441\u0435\u0440\u0442\u0438\u0444\u0456\u043a\u043e\u0432\u0430\u043d\u043e\u044e, \u0435\u0442\u0438\u0447\u043d\u043e\u044e \u043a\u043e\u043c\u043f\u0430\u043d\u0456\u0454\u044e, \u044f\u043a\u0430 \u0446\u0456\u043d\u0443\u0454 \u0437\u0440\u043e\u0441\u0442\u0430\u043d\u043d\u044f, \u0431\u0435\u0437\u043f\u0435\u043a\u0443 \u0442\u0430 \u0432\u043f\u043b\u0438\u0432 \u043d\u0430 \u0441\u0443\u0441\u043f\u0456\u043b\u044c\u0441\u0442\u0432\u043e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-vt6pfnh1 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"vt6pfnh1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/deva.cz\/wp-content\/uploads\/2026\/02\/deva-nutrition-organic-baby-food-producer.png\" class=\"attachment-full size-full wp-image-482\" alt=\"\" srcset=\"https:\/\/deva.cz\/wp-content\/uploads\/2026\/02\/deva-nutrition-organic-baby-food-producer.png 1920w, https:\/\/deva.cz\/wp-content\/uploads\/2026\/02\/deva-nutrition-organic-baby-food-producer-300x169.png 300w, https:\/\/deva.cz\/wp-content\/uploads\/2026\/02\/deva-nutrition-organic-baby-food-producer-1024x576.png 1024w, https:\/\/deva.cz\/wp-content\/uploads\/2026\/02\/deva-nutrition-organic-baby-food-producer-768x432.png 768w, https:\/\/deva.cz\/wp-content\/uploads\/2026\/02\/deva-nutrition-organic-baby-food-producer-1536x864.png 1536w, https:\/\/deva.cz\/wp-content\/uploads\/2026\/02\/deva-nutrition-organic-baby-food-producer-18x10.png 18w, https:\/\/deva.cz\/wp-content\/uploads\/2026\/02\/deva-nutrition-organic-baby-food-producer-600x338.png 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a85777 e-flex e-con-boxed e-con e-parent\" data-id=\"8a85777\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-010920c elementor-widget elementor-widget-heading\" data-id=\"010920c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u041f\u043e\u0442\u043e\u0447\u043d\u0456 \u0432\u0430\u043a\u0430\u043d\u0441\u0456\u0457<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8465d30 e-flex e-con-boxed e-con e-parent\" data-id=\"8465d30\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0de30e6 elementor-widget elementor-widget-text-editor\" data-id=\"0de30e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0410\u043a\u0442\u0443\u0430\u043b\u0456\u0437\u043e\u0432\u0430\u043d\u043e 10.3<\/span><\/span><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">.2026<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-042cb3b e-flex e-con-boxed e-con e-parent\" data-id=\"042cb3b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c3a4304 e-con-full e-flex e-con e-child\" data-id=\"c3a4304\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb97fca elementor-widget elementor-widget-heading\" data-id=\"cb97fca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Skladov\u00fd d\u011bln\u00edk- \u0159idi\u010d VZV<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e565c3 e-flex e-con-boxed e-con e-parent\" data-id=\"5e565c3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-40a1992 e-con-full e-flex e-con e-child\" data-id=\"40a1992\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-931bf69 elementor-widget elementor-widget-text-editor\" data-id=\"931bf69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Mzda (v\u010detn\u011b benef\u016f): a\u017e 36 900,-<\/strong><\/p><p><strong>N\u00e1pl\u0148 pr\u00e1ce:<\/strong><\/p><ul><li>\u0437\u0430\u0457\u0436\u0434\u0436\u0435\u043d\u0456 \u0432\u0438\u043a\u043b\u0430\u0434\u043a\u0438 \u043a\u0430\u043c\u0456\u043e\u043d\u0443<\/li><li>\u043d\u0430\u043a\u043b\u0430\u0434\u0430\u043d\u043d\u044f \u0442\u0430 \u0432\u0438\u043a\u043b\u0430\u0434\u0430\u043d\u043d\u044f \u043e\u0431\u0430\u043b\u0443, \u0446\u0435\u0440\u043a\u0432\u0435\u043d\u043e\u0433\u043e \u044f\u0439\u0446\u044f; \u043d\u0430\u043a\u043b\u0430\u0434\u0430\u043d\u043d\u044f \u0433\u0430\u0440\u044f\u0447\u0438\u0445 \u0432\u0438\u0440\u043e\u0431\u0456\u0432; \u043d\u0430\u043a\u043b\u0430\u0434\u0430\u043d\u043d\u044f \u0433\u0430\u0440\u044f\u0447\u0438\u0445 \u0432\u0438\u0440\u043e\u0431\u0456\u0432 \u043d\u0430 \u043a\u0430\u043c'\u044f\u043d\u0443 \u043f\u043b\u0438\u0442\u0443<\/li><li>pr\u00e1ce s modern\u00edmi elektrick\u00fdmi voz\u00edky v potravin\u00e1\u0159sk\u00e9 v\u00fdrob\u011b s nejvy\u0161\u0161\u00edmi hygienick\u00fdmi standarty<\/li><\/ul><p><strong>O\u010dek\u00e1v\u00e1me:<\/strong><\/p><ul><li>vzd\u011bl\u00e1n\u00ed min. SO ukon\u010den\u00e9 v\u00fdu\u010dn\u00edm listem<\/li><li>opr\u00e1vn\u011bn\u00ed k \u0159\u00edzen\u00ed VZV v\u00fdhodou<\/li><li>t\u00fdmov\u00e1 spolupr\u00e1ce<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-08a6c5b e-con-full e-flex e-con e-child\" data-id=\"08a6c5b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19ce078 elementor-widget elementor-widget-text-editor\" data-id=\"19ce078\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0412\u0438\u0445\u043e\u0434\u0438:<\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5 t\u00fddn\u016f dovolen\u00e9<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">ro\u010dn\u00ed valorizace mzdy<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">p\u0159\u00edsp\u011bvek na dopravu<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">karta Benefit Plus<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">stravenkov\u00fd pau\u0161\u00e1l, dotovan\u00e9 stravov\u00e1n\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">p\u0159\u00edsp\u011bvek na penzijn\u00ed poji\u0161t\u011bn\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">prodej v\u00fdrobk\u016f za zv\u00fdhodn\u011bn\u00e9 ceny<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">dary p\u0159i \u017eivotn\u00edm a praktivn\u00edm jubileu<\/span><\/span><\/li><\/ul><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041d\u0430\u0431\u0456\u0436\u0438\u043c\u043e:<\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">sm\u011bnn\u00fd re\u017eim, \u00favazek 37,5 hodin\/t\u00fdden<\/span><\/span><\/li><li>voln\u00e9 v\u00edkendy<\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">zau\u010den\u00ed a podpora od zku\u0161en\u00fdch koleg\u016f<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">pr\u00e1ci ve stabiln\u00ed spole\u010dnosti \u0437 letitou histori\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">n\u00e1stup mo\u017en\u00fd ihned<\/span><\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4079285 e-flex e-con-boxed e-con e-parent\" data-id=\"4079285\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-77299fa e-con-full e-flex e-con e-child\" data-id=\"77299fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2a224a4 e-con-full e-flex e-con e-child\" data-id=\"2a224a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95e0d35 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"95e0d35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e0983d elementor-widget elementor-widget-heading\" data-id=\"7e0983d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u041e\u043f\u0435\u0440\u0430\u0442\u043e\u0440 - \u0441\u0430\u043d\u0456\u0442\u0430\u0440\u043d\u0438\u0439 \u0442\u0435\u0445\u043d\u0456\u043a<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e49e761 e-flex e-con-boxed e-con e-parent\" data-id=\"e49e761\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6ea66fc e-con-full e-flex e-con e-child\" data-id=\"6ea66fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-045f391 elementor-widget elementor-widget-text-editor\" data-id=\"045f391\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Mzda (v\u010detn\u011b benef\u016f): a\u017e 37 700,-<\/strong><\/p><p><strong>N\u00e1pl\u0148 pr\u00e1ce:<\/strong><\/p><ul><li>\u0441\u0430\u043d\u0456\u0442\u0430\u0440\u043d\u0456 \u0443\u043c\u043e\u0432\u0438, \u043f\u043b\u0430\u043d\u0438 \u0442\u0430 \u043f\u0435\u0440\u0435\u0433\u043b\u044f\u0434 \u0441\u0430\u043d\u0456\u0442\u0430\u0440\u043d\u0438\u0445 \u043d\u043e\u0440\u043c<\/li><li>zajistit bezpe\u010dn\u00fd a plynul\u00fd provoz stroje<\/li><li>\u043e\u0431'\u0454\u0434\u043d\u0430\u043d\u0430 \u0432\u0438\u0440\u043e\u0431\u043d\u0438\u0447\u0430 \u0442\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0456\u044f<\/li><li>postupn\u00e9 za\u0161kolov\u00e1n\u00ed na NZV<\/li><li>postupn\u00e9 za\u0161kolov\u00e1n\u00ed na p\u0159\u00edpravu produktov\u00fdch sm\u011bs\u00ed<\/li><\/ul><p><strong>O\u010dek\u00e1v\u00e1me:<\/strong><\/p><ul><li>vzd\u011bl\u00e1n\u00ed min. SO ukon\u010den\u00e9 v\u00fdu\u010dn\u00edm listem<\/li><li>t\u00fdmovou pr\u00e1ci<\/li><li>\u0433\u043d\u0443\u0447\u043a\u0456\u0441\u0442\u044c \u0442\u0430 \u0430\u043a\u0442\u0438\u0432\u043d\u0438\u0439 \u0440\u043e\u0437\u0432\u0438\u0442\u043e\u043a<\/li><li>dobr\u00fd zdravotn\u00ed stav<\/li><li>\u043c\u0430\u043d\u0443\u0430\u043b\u044c\u043d\u0430 \u0437\u0440\u0443\u0447\u043d\u0456\u0441\u0442\u044c<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b669fa5 e-con-full e-flex e-con e-child\" data-id=\"b669fa5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-609d5a7 elementor-widget elementor-widget-text-editor\" data-id=\"609d5a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0412\u0438\u0445\u043e\u0434\u0438:<\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5 t\u00fddn\u016f dovolen\u00e9<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">ro\u010dn\u00ed valorizace mzdy<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">p\u0159\u00edsp\u011bvek na dopravu<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">karta Benefit Plus<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">stravenkov\u00fd pau\u0161\u00e1l, dotovan\u00e9 stravov\u00e1n\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">p\u0159\u00edsp\u011bvek na penzijn\u00ed poji\u0161t\u011bn\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">prodej v\u00fdrobk\u016f za zv\u00fdhodn\u011bn\u00e9 ceny<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">dary p\u0159i \u017eivotn\u00edm a praktivn\u00edm jubileu<\/span><\/span><\/li><\/ul><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041d\u0430\u0431\u0456\u0436\u0438\u043c\u043e:<\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">sm\u011bnn\u00fd re\u017eim, \u00favazek 37,5 hodin\/t\u00fdden<\/span><\/span><\/li><li>voln\u00e9 v\u00edkendy<\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">zau\u010den\u00ed a podpora od zku\u0161en\u00fdch koleg\u016f<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">pr\u00e1ci ve stabiln\u00ed spole\u010dnosti \u0437 letitou histori\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">n\u00e1stup mo\u017en\u00fd ihned<\/span><\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3fc63f e-flex e-con-boxed e-con e-parent\" data-id=\"c3fc63f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f0d6317 e-con-full e-flex e-con e-child\" data-id=\"f0d6317\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4ba888e e-con-full e-flex e-con e-child\" data-id=\"4ba888e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-58008fd e-con-full e-flex e-con e-child\" data-id=\"58008fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b32f8c elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6b32f8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c91480a elementor-widget elementor-widget-heading\" data-id=\"c91480a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u041e\u043f\u0435\u0440\u0430\u0442\u043e\u0440 \u0440\u043e\u0431\u043e\u0447\u0438\u0445 \u043f\u043e\u0441\u0438\u043b\u0430\u043d\u044c<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef45826 e-flex e-con-boxed e-con e-parent\" data-id=\"ef45826\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3db96f8 e-con-full e-flex e-con e-child\" data-id=\"3db96f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8493179 elementor-widget elementor-widget-text-editor\" data-id=\"8493179\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Mzda (v\u010detn\u011b benef\u016f): a\u017e 32 700,-<\/strong><\/p><p><strong>N\u00e1pl\u0148 pr\u00e1ce:<\/strong><\/p><ul><li>obsluha pln\u011b automatick\u00e9 v\u00fdrobn\u00ed linky<\/li><li>dopl\u0148ov\u00e1n\u00ed surovin pot\u0159ebn\u00fdch k v\u00fdrob\u011b<\/li><li>pr\u00e1ce p\u0159ev\u00e1\u017en\u011b vestoje<\/li><li>ve v\u0161em pot\u0159ebn\u00e9m V\u00e1s zau\u010d\u00edme<\/li><\/ul><p><strong>O\u010dek\u00e1v\u00e1me:<\/strong><\/p><ul><li>vzd\u011bl\u00e1n\u00ed z\u00e1kladn\u00ed nebo SO ukon\u010den\u00e9 v\u00fdu\u010dn\u00edm listem<\/li><li>t\u00fdmovou pr\u00e1ci<\/li><li>\u0433\u043d\u0443\u0447\u043a\u0456\u0441\u0442\u044c \u0442\u0430 \u0430\u043a\u0442\u0438\u0432\u043d\u0438\u0439 \u0440\u043e\u0437\u0432\u0438\u0442\u043e\u043a<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-247f394 e-con-full e-flex e-con e-child\" data-id=\"247f394\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-236f736 elementor-widget elementor-widget-text-editor\" data-id=\"236f736\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0412\u0438\u0445\u043e\u0434\u0438:<\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5 t\u00fddn\u016f dovolen\u00e9<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">ro\u010dn\u00ed valorizace mzdy<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">p\u0159\u00edsp\u011bvek na dopravu<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">karta Benefit Plus<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">stravenkov\u00fd pau\u0161\u00e1l, dotovan\u00e9 stravov\u00e1n\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">p\u0159\u00edsp\u011bvek na penzijn\u00ed poji\u0161t\u011bn\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">prodej v\u00fdrobk\u016f za zv\u00fdhodn\u011bn\u00e9 ceny<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">dary p\u0159i \u017eivotn\u00edm a praktivn\u00edm jubileu<\/span><\/span><\/li><\/ul><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041d\u0430\u0431\u0456\u0436\u0438\u043c\u043e:<\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">sm\u011bnn\u00fd re\u017eim, \u00favazek 37,5 hodin\/t\u00fdden<\/span><\/span><\/li><li>voln\u00e9 v\u00edkendy<\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">zau\u010den\u00ed a podpora od zku\u0161en\u00fdch koleg\u016f<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">pr\u00e1ci ve stabiln\u00ed spole\u010dnosti \u0437 letitou histori\u00ed<\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">n\u00e1stup mo\u017en\u00fd ihned<\/span><\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b2b9b7 e-flex e-con-boxed e-con e-parent\" data-id=\"7b2b9b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ae13813 e-con-full e-flex e-con e-child\" data-id=\"ae13813\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-360c115 e-con-full e-flex e-con e-child\" data-id=\"360c115\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b936f45 e-con-full e-flex e-con e-child\" data-id=\"b936f45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-483c7b8 e-con-full e-flex e-con e-child\" data-id=\"483c7b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dacfa48 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dacfa48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,6,13,12,13S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45746d5 elementor-widget elementor-widget-heading\" data-id=\"45746d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u041f\u0430\u043d\u0435 \u0421\u043c\u0454\u043d\u044c<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dda94fa e-flex e-con-boxed e-con e-parent\" data-id=\"dda94fa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-19fee1f e-con-full e-flex e-con e-child\" data-id=\"19fee1f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2772fcb elementor-widget elementor-widget-text-editor\" data-id=\"2772fcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Mzda (v\u010detn\u011b benef\u016f): a\u017e 45 500,-<\/span><\/span><\/span><\/span><\/strong><\/p><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0412\u0438\u0445\u043e\u0434\u0438:<\/span><\/span><\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">5 t\u00fddn\u016f dovolen\u00e9<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">ro\u010dn\u00ed valorizace mzdy<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">p\u0159\u00edsp\u011bvek na dopravu<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">karta Benefit Plus<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">stravenkov\u00fd pau\u0161\u00e1l, dotovan\u00e9 ob\u011bdy<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">p\u0159\u00edsp\u011bvek na penzijn\u00ed p\u0159ipoji\u0161t\u011bn\u00ed<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">prodej v\u00fdrobk\u016f za zv\u00fdhodn\u011bn\u00e9 ceny<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">dary p\u0159i \u017eivotn\u00edm a praktivn\u00edm jubileu<\/span><\/span><\/span><\/span><\/li><\/ul><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u041d\u0430\u0431\u0456\u0436\u0438\u043c\u043e:<\/span><\/span><\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">sm\u011bnn\u00fd re\u017eim, \u00favazek 37,5 h.<\/span><\/span><\/span><\/span><\/li><li>voln\u00e9 v\u00edkendy<\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">zau\u010den\u00ed a podpora od zku\u0161en\u00fdch koleg\u016f<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">pr\u00e1ci ve stabiln\u00ed spole\u010dnosti \u0437 letitou histori\u00ed<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">n\u00e1stup mo\u017en\u00fd ihned<\/span><\/span><\/span><\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4783662 e-con-full e-flex e-con e-child\" data-id=\"4783662\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef4fc9f elementor-widget elementor-widget-text-editor\" data-id=\"ef4fc9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">N\u00e1pl\u0148 pr\u00e1ce:<\/span><\/span><\/span><\/span><\/strong><\/p><ul><li>veden\u00ed pod\u0159\u00edzen\u00fdch<\/li><li>\u043e\u0440\u0433\u0430\u043d\u0456\u0437\u043e\u0432\u0443\u0432\u0430\u0442\u0438 \u0432\u0438\u0440\u043e\u0431\u043d\u0438\u0447\u0456 \u043f\u0456\u0434\u043f\u0440\u0438\u0454\u043c\u0441\u0442\u0432\u0430, \u0430 \u0442\u0430\u043a\u043e\u0436 \u0432\u0445\u043e\u0434\u0438\u0442\u0438 \u0434\u043e \u0441\u043a\u043b\u0430\u0434\u0443 \u0434\u0435\u0440\u0436\u0430\u0432\u043d\u0438\u0445 \u043f\u0456\u0434\u043f\u0440\u0438\u0454\u043c\u0441\u0442\u0432<\/li><li>zaji\u0161t\u011bn\u00ed bezpe\u010dn\u00e9ho a plynul\u00e9ho provozu v\u00fdroby<\/li><li>\u043a\u043e\u043d\u0442\u0440\u043e\u043b\u044c \u0434\u043e\u0442\u0440\u0438\u043c\u0430\u043d\u043d\u044f \u0433\u0456\u0433\u0456\u0454\u043d\u0456\u0447\u043d\u0438\u0445 \u0442\u0430 \u043a\u0432\u0430\u043b\u0456\u0444\u0456\u043a\u0430\u0446\u0456\u0439\u043d\u0438\u0445 \u043d\u043e\u0440\u043c<\/li><li>\u00fa\u010dast na pravideln\u00fdch porad\u00e1ch v\u00fdroby<\/li><li>\u043d\u0430\u0432\u0447\u0430\u043d\u043d\u044f \u043d\u043e\u0432\u0438\u0445 \u0441\u043f\u0435\u0446\u0456\u0430\u043b\u044c\u043d\u043e\u0441\u0442\u0435\u0439<\/li><\/ul><p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">O\u010dek\u00e1v\u00e1me:<\/span><\/span><\/span><\/span><\/strong><\/p><ul><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">vzd\u011bl\u00e1n\u00ed min. SO ukon\u010den\u00e9 v\u00fdu\u010dn\u00edm listem<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">t\u00fdmovou pr\u00e1ci<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u0433\u043d\u0443\u0447\u043a\u0456\u0441\u0442\u044c \u0442\u0430 \u0430\u043a\u0442\u0438\u0432\u043d\u0438\u0439 \u0440\u043e\u0437\u0432\u0438\u0442\u043e\u043a<\/span><\/span><\/span><\/span><\/li><li><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">schopnost veden\u00ed t\u00fdmu<\/span><\/span><\/span><\/span><\/li><li>dobr\u00fd zdravotn\u00ed stav - pr\u00e1ce vestoje<\/li><li>\u043e\u0444\u0456\u0446\u0456\u0439\u043d\u0430 \u0456\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0456\u044f \u043f\u0440\u043e HACCP<\/li><li>zku\u0161enosti na obdobn\u00e9 pozici<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b19fdb2 e-flex e-con-boxed e-con e-parent\" data-id=\"b19fdb2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a939ff8 elementor-widget elementor-widget-text-editor\" data-id=\"a939ff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><span style=\"font-style: inherit; font-weight: inherit;\">\u0423 \u0440\u0430\u0437\u0456 \u0432\u0438\u043d\u0438\u043a\u043d\u0435\u043d\u043d\u044f \u0437\u0430\u043f\u0438\u0442\u0443 \u043f\u0440\u043e \u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u0456 \u043f\u0440\u043e\u043f\u043e\u0437\u0438\u0446\u0456\u0457, \u0431\u0443\u0434\u044c \u043b\u0430\u0441\u043a\u0430, \u0437\u0432'\u044f\u0436\u0456\u0442\u044c\u0441\u044f \u0437 \u043d\u0430\u043c\u0438: <\/span><\/span><a href=\"mailto:prace@deva.cz\" target=\"_blank\" rel=\"noopener\"><b><span style=\"font-style: inherit; font-weight: inherit;\">prace@deva.cz<\/span><\/b><\/a><span style=\"font-weight: 400;\"><span style=\"font-style: inherit; font-weight: inherit;\">, nebo tel.\u00a0<\/span><\/span><span style=\"font-weight: inherit;\"><b><strong><span style=\"font-style: inherit; font-weight: inherit;\">491 439 282.<\/span><\/strong><\/b><\/span><\/p><p style=\"font-weight: 400;\"><b>\u00a0<\/b><\/p><p style=\"font-weight: 400;\"><span style=\"font-style: inherit; font-weight: inherit;\">Na\u0161e inzer\u00e1ty jsou v n\u011bkter\u00fdch p\u0159\u00edpadech ps\u00e1ny v \u017eensk\u00e9m nebo mu\u017esk\u00e9m rod\u011b. Tento postup byl zvolen v\u00fdhradn\u011b proto, aby bylo dosa\u017eeno co nejvy\u0161\u0161\u00ed plynulosti textu. \u0423 \u0434\u0430\u043d\u043e\u043c\u0443 \u043f\u043e\u0441\u0456\u0431\u043d\u0438\u043a\u0443 \u043d\u0435 \u043c\u0456\u0441\u0442\u0438\u0442\u044c\u0441\u044f \u0433\u0435\u043d\u0434\u0435\u0440\u043d\u043e\u0457 \u0434\u0438\u0441\u043a\u0440\u0438\u043c\u0456\u043d\u0430\u0446\u0456\u0457, \u0430 \u0442\u0430\u043a\u043e\u0436 \u0434\u0438\u0441\u043a\u0440\u0438\u043c\u0456\u043d\u0430\u0446\u0456\u0439\u043d\u043e\u0433\u043e \u043f\u0456\u0434\u0445\u043e\u0434\u0443 \u0434\u043e \u043d\u0430\u0448\u0438\u0445 \u0432\u0456\u0434\u043d\u043e\u0441\u0438\u043d \u0437 \u0443\u0447\u043d\u044f\u043c\u0438 \u0442\u0430 \u0432\u0447\u0438\u0442\u0435\u043b\u044f\u043c\u0438 \u0443 \u0440\u0456\u0437\u043d\u0438\u0445 \u0441\u0444\u0435\u0440\u0430\u0445 \u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u043e\u0457 \u0434\u0456\u044f\u043b\u044c\u043d\u043e\u0441\u0442\u0456.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef115b1 twbb_section e-flex e-con-boxed e-con e-parent\" data-id=\"ef115b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15738b0 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"15738b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u041d\u0430\u043f\u0438\u0448\u0456\u0442\u044c \u043d\u0430\u043c\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t <a href='mailto:info@deva.cz'>info@deva.cz<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c73f5b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3c73f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0422\u0435\u043b\u0435\u0444\u043e\u043d\u0443\u0439\u0442\u0435 \u043d\u0430\u043c\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href='tel:+420491439111'>+420 491 439 111<\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9977d52 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9977d52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u0417\u0430\u0432\u0456\u0442\u0430\u0439\u0442\u0435 \u0434\u043e \u043d\u0430\u0441\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u041c\u0438 \u0437\u043d\u0430\u0445\u043e\u0434\u0438\u043c\u043e\u0441\u044f \u0437\u0430 \u0430\u0434\u0440\u0435\u0441\u043e\u044e <a href='https:\/\/maps.app.goo.gl\/Z7urBAghyHuDrZai7'>\u0413\u0435\u043d\u0435\u0440\u0430\u043b\u0430 \u041a\u043b\u0430\u043f\u0430\u043b\u043a\u0430 519, 549 01 \u041d\u043e\u0432\u0435 \u041c\u0456\u0441\u0442\u043e \u043d\u0430\u0434 \u041c\u0435\u0442\u0443\u0457, \u0427\u0435\u0441\u044c\u043a\u0430 \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0456\u043a\u0430<\/a>. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Join Our Team at Deva Nutrition Become part of a dedicated team committed to quality, sustainability, and innovation. At Deva Nutrition a.s., we foster a collaborative and inclusive work environment where your contributions help us deliver healthy, organic products across the world. Discover the benefits of working with a certified, ethical company that values growth, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"two_page_speed":[],"footnotes":""},"class_list":["post-423","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/deva.cz\/uk\/wp-json\/wp\/v2\/pages\/423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deva.cz\/uk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/deva.cz\/uk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/deva.cz\/uk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/deva.cz\/uk\/wp-json\/wp\/v2\/comments?post=423"}],"version-history":[{"count":0,"href":"https:\/\/deva.cz\/uk\/wp-json\/wp\/v2\/pages\/423\/revisions"}],"wp:attachment":[{"href":"https:\/\/deva.cz\/uk\/wp-json\/wp\/v2\/media?parent=423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}